{"id":3679,"date":"2023-08-17T06:02:00","date_gmt":"2023-08-17T04:02:00","guid":{"rendered":"https:\/\/expert-only.com\/?p=3679"},"modified":"2023-10-30T18:07:43","modified_gmt":"2023-10-30T17:07:43","slug":"comment-creer-un-tableau-excel","status":"publish","type":"post","link":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/","title":{"rendered":"Comment cr\u00e9er un tableau Excel ?"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\" id=\"h-tutoriel-pas-a-pas-pour-creer-un-tableau-depuis-une-plage-de-donnees-avec-excel-pour-les-trier-les-additionner-et-les-filtrer\"><em>Tutoriel pas \u00e0 pas pour cr\u00e9er un tableau depuis une plage de donn\u00e9es avec Excel pour les trier, les additionner et les filtrer.<\/em><\/h4>\n\n\n\n<p>Comment cr\u00e9er un tableau Excel et trier les colonnes, puis filtrer les donn\u00e9es ? Cr\u00e9er tout d&rsquo;abord les lignes et les colonnes requises. Remplir le tableau avec des donn\u00e9es et le transformer en tableau avec des ent\u00eates. Une fois sous forme de tableau, il est possible de trier et filtrer les donn\u00e9es plus facilement. Pour travailler avec les donn\u00e9es, il est essentiel de trouver des moyens de les exploiter de mani\u00e8re pertinente. La premi\u00e8re \u00e9tape consiste \u00e0 comprendre les donn\u00e9es dont vous disposez, puis \u00e0 les trier et \u00e0 les analyser en fonction des besoins.<\/p>\n\n\n\n<p><strong>Les tableaux Excel sont un excellent moyen d&rsquo;organiser les donn\u00e9es.<\/strong> Ils peuvent \u00eatre consid\u00e9r\u00e9s comme l&rsquo;\u00e9quivalent d&rsquo;une liste organis\u00e9e dans un tableur. Lorsque vous regardez un tableau Excel, se demander quelles questions doivent \u00eatre pos\u00e9es et quelles donn\u00e9es vous voulez voir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-tutoriel-en-video-pour-creer-un-tableau-excel\">Tutoriel en vid\u00e9o pour cr\u00e9er un tableau Excel<\/h3>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/DlQE4pYmE04?si=wueT6QcbmJcdgoeP&amp;controls=0\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n\n\n\n<h3 class=\"wp-block-heading\">Qu&rsquo;est-ce qu&rsquo;un tableau Excel ?<\/h3>\n\n\n\n<p>Un tableau Excel est un type d&rsquo;objet tr\u00e8s utilis\u00e9 par les professionnels de la donn\u00e9e et surtout de la finance, comme les experts comptables et les contr\u00f4leurs de gestion. A ne pas confondre avec le <a href=\"https:\/\/www.tableau.com\/fr-fr\" target=\"_blank\" rel=\"noreferrer noopener\">logiciel Tableau<\/a>. On peut le d\u00e9finir comme un moyen de stocker des donn\u00e9es dans un format structur\u00e9. Les tableaux sont utiles pour stocker des donn\u00e9es qui ont une structure en lignes et en colonnes.<\/p>\n\n\n\n\n\n\n<p><strong><em>Cette premi\u00e8re partie consiste \u00e0 cr\u00e9er un tableau et ins\u00e9rer des donn\u00e9es \u00e0 la main pour remplir les lignes et les colonnes, puis ajouter une formule pour calculer le total d&rsquo;une ligne.<\/em><\/strong><\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#1-creer-un-fichier-excel-et-ajouter-les-colonnes-du-tableau\" >1. Cr\u00e9er un fichier Excel et ajouter les colonnes du tableau<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#2-generer-les-noms-de-colonnes-excel-automatiquement\" >2. G\u00e9n\u00e9rer les noms de colonnes Excel automatiquement<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#3-ajouter-les-entetes-et-le-total-des-lignes\" >3. Ajouter les ent\u00eates et le total des lignes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#4-dupliquer-les-lignes-excel-avec-la-formule\" >4. Dupliquer les lignes Excel avec la formule<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#5-selectionner-toutes-les-cellules-remplies\" >5. S\u00e9lectionner toutes les cellules remplies<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#6-mettre-les-donnees-sous-forme-de-tableau-excel\" >6. Mettre les donn\u00e9es sous forme de tableau Excel<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#7-ajouter-une-ligne-des-totaux-en-bas-du-tableau-excel\" >7. Ajouter une ligne des totaux en bas du tableau Excel<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#8-trier-les-donnees-du-tableau-excel\" >8. Trier les donn\u00e9es du tableau Excel<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1-creer-un-fichier-excel-et-ajouter-les-colonnes-du-tableau\"><\/span>1. Cr\u00e9er un fichier Excel et ajouter les colonnes du tableau<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Cr\u00e9er un <strong><a href=\"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-fichier-excel\/\">nouveau fichier Excel<\/a><\/strong>, puis <strong>ajouter les colonnes<\/strong>. Dans cet exemple,  c&rsquo;est un budget pr\u00e9visionnel mois pas mois, sur plusieurs ann\u00e9es. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"890\" height=\"292\" src=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_1_selectionner_mois_janvier_fevrier.png\" alt=\"Cr\u00e9er une plage de donn\u00e9es Excel comme source du tableau\" class=\"wp-image-3680\" srcset=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_1_selectionner_mois_janvier_fevrier.png 890w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_1_selectionner_mois_janvier_fevrier-300x98.png 300w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_1_selectionner_mois_janvier_fevrier-768x252.png 768w\" sizes=\"auto, (max-width: 890px) 100vw, 890px\" \/><figcaption class=\"wp-element-caption\"><em>Cr\u00e9er une plage de donn\u00e9es Excel comme source du tableau<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2-generer-les-noms-de-colonnes-excel-automatiquement\"><\/span>2. G\u00e9n\u00e9rer les noms de colonnes Excel automatiquement<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Pour g\u00e9n\u00e9rer la suite de la liste des mois en toutes lettres, <strong>s\u00e9lectionner les deux cellules<\/strong> Janvier et F\u00e9vrier. <strong>Cliquer sur la petite croix<\/strong> et <strong>maintenir puis faire glisser la souris<\/strong> jusqu&rsquo;\u00e0 D\u00e9cembre. Le r\u00e9sultat est donc une colonne ann\u00e9e et douze colonnes pour les mois.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"174\" src=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_2_glisser_jusque_decembre-1024x174.png\" alt=\"Faire glisser la s\u00e9lection Excel pour g\u00e9n\u00e9rer automatiquement les noms de mois\" class=\"wp-image-3681\" srcset=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_2_glisser_jusque_decembre-1024x174.png 1024w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_2_glisser_jusque_decembre-300x51.png 300w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_2_glisser_jusque_decembre-768x131.png 768w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_2_glisser_jusque_decembre.png 1145w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Faire glisser la s\u00e9lection Excel pour g\u00e9n\u00e9rer automatiquement les noms de mois<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3-ajouter-les-entetes-et-le-total-des-lignes\"><\/span>3. Ajouter les ent\u00eates et le total des lignes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ajouter ensuite les ann\u00e9es de 2020 \u00e0 2025, puis la colonne Total \u00e0 droite, <strong>calcul\u00e9e avec une formule Excel<\/strong> simple. La formule Excel dans la cellule utilise la fonction SOMME : <\/p>\n\n\n\n<pre class=\"EnlighterJSRAW\" data-enlighter-language=\"visualbasic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">=SOMME(C3:N3)<\/pre>\n\n\n\n<p>Pour faciliter la cr\u00e9ation de la formule, \u00e9crire la fonction SOMME puis  s\u00e9lectionner la premi\u00e8re ligne des montants de Janvier \u00e0 D\u00e9cembre.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"197\" src=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_3_ajouter_total_par_annee-1024x197.png\" alt=\"Ajouter le total annuel avec une formule\" class=\"wp-image-3682\" srcset=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_3_ajouter_total_par_annee-1024x197.png 1024w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_3_ajouter_total_par_annee-300x58.png 300w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_3_ajouter_total_par_annee-768x148.png 768w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_3_ajouter_total_par_annee.png 1226w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4-dupliquer-les-lignes-excel-avec-la-formule\"><\/span>4. Dupliquer les lignes Excel avec la formule<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Pour cr\u00e9er rapidement un tableau Excel, dupliquer les lignes. Pour cela, <strong>s\u00e9lectionner la premi\u00e8re ligne de Janvier \u00e0 la colonne Total<\/strong>. Puis <strong>faire glisser vers le bas<\/strong> comme sur cette capture d&rsquo;\u00e9cran. Cette zone de cellules brutes, source du tableau, n&rsquo;est pas filtr\u00e9e ni mise en forme.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"190\" src=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_4_glisser_total_par_annee-1024x190.png\" alt=\"Dupliquer les lignes du tableau Excel et le total\" class=\"wp-image-3683\" srcset=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_4_glisser_total_par_annee-1024x190.png 1024w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_4_glisser_total_par_annee-300x56.png 300w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_4_glisser_total_par_annee-768x142.png 768w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_4_glisser_total_par_annee.png 1274w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Un autre tutoriel utile, cette fois sur <a href=\"https:\/\/expert-only.com\/fr\/excel\/raccourcis-excel-de-selection\/\"><strong>les raccourcis Excel pour s\u00e9lectionner des cellules<\/strong><\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-tutoriels-sql-et-it wp-block-embed-tutoriels-sql-et-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"X9nMk2QbUH\"><a href=\"https:\/\/expert-only.com\/fr\/excel\/raccourcis-excel-de-selection\/\">Les meilleurs raccourcis Excel de s\u00e9lection de cellules<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0Les meilleurs raccourcis Excel de s\u00e9lection de cellules\u00a0\u00bb &#8212; Tutoriels SQL et IT\" src=\"https:\/\/expert-only.com\/fr\/excel\/raccourcis-excel-de-selection\/embed\/#?secret=Vdwx0j4e15#?secret=X9nMk2QbUH\" data-secret=\"X9nMk2QbUH\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong><em>Cette deuxi\u00e8me partie explique comment cr\u00e9er le tableau Excel proprement dit, c&rsquo;est \u00e0 dire le mettre en forme pour trier les donn\u00e9es.<\/em><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5-selectionner-toutes-les-cellules-remplies\"><\/span>5. S\u00e9lectionner toutes les cellules remplies<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>S\u00e9lectionner toutes les cellules contigu\u00ebs, pour cela, <strong>cliquer sur la cellule en haut \u00e0 gauche<\/strong>. Puis utiliser le raccourci <strong>CTRL + A<\/strong> pour s\u00e9lectionner toutes les donn\u00e9es. Cette table ou zone Excel est en quelque sorte le tableau, sans mise en forme.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"221\" src=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_5_selectionner_tableau_entier-1024x221.png\" alt=\"S\u00e9lectionner toutes les donn\u00e9es d'un fichier Excel pour mettre en forme de tableau\" class=\"wp-image-3684\" srcset=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_5_selectionner_tableau_entier-1024x221.png 1024w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_5_selectionner_tableau_entier-300x65.png 300w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_5_selectionner_tableau_entier-768x166.png 768w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_5_selectionner_tableau_entier.png 1248w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"6-mettre-les-donnees-sous-forme-de-tableau-excel\"><\/span>6. Mettre les donn\u00e9es sous forme de tableau Excel<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Sous Accueil, choisir ensuite l&rsquo;option <strong>Mettre sous forme de tableau<\/strong>. <strong>Choisir la couleur et le style de tableau<\/strong>, ici c&rsquo;est un tableau Orange.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"524\" src=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_6_mettre_sous_forme_de_tableau.png\" alt=\"Cr\u00e9er le tableau Excel depuis le menu Principal\" class=\"wp-image-3685\" srcset=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_6_mettre_sous_forme_de_tableau.png 860w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_6_mettre_sous_forme_de_tableau-300x183.png 300w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_6_mettre_sous_forme_de_tableau-768x468.png 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><figcaption class=\"wp-element-caption\"><em>Cr\u00e9er le tableau Excel depuis le menu Principal<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p>Ensuite, cocher l&rsquo;option <strong>Mon tableau comporte des en-t\u00eates<\/strong>, pour indiquer de prendre en compte les en-t\u00eates pr\u00e9existants. Cette action ne rajoutera donc pas de ligne au tableau. Cr\u00e9er un tableau Excel avec les ent\u00eates en amont permet de mieux g\u00e9rer les donn\u00e9es.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"332\" src=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_7_tableau_comporte_des_entetes-1024x332.png\" alt=\"Utiliser les ent\u00eates d\u00e9j\u00e0 pr\u00e9sentes dans la plage de donn\u00e9es Excel\" class=\"wp-image-3686\" srcset=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_7_tableau_comporte_des_entetes-1024x332.png 1024w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_7_tableau_comporte_des_entetes-300x97.png 300w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_7_tableau_comporte_des_entetes-768x249.png 768w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_7_tableau_comporte_des_entetes.png 1113w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Utiliser les ent\u00eates d\u00e9j\u00e0 pr\u00e9sentes dans la plage de donn\u00e9es Excel<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"7-ajouter-une-ligne-des-totaux-en-bas-du-tableau-excel\"><\/span>7. Ajouter une ligne des totaux en bas du tableau Excel<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ajouter la ligne des totaux pour obtenir le total g\u00e9n\u00e9ral avec toutes les ann\u00e9es.  Faire un <strong>clic-droit<\/strong> sur le tableau Excel, puis choisir <strong>Table <\/strong>et enfin s\u00e9lectionner <strong>Ligne des totaux<\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"607\" height=\"485\" src=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_8_ajouter_lignes_des_totaux.png\" alt=\"\" class=\"wp-image-3687\" srcset=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_8_ajouter_lignes_des_totaux.png 607w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_8_ajouter_lignes_des_totaux-300x240.png 300w\" sizes=\"auto, (max-width: 607px) 100vw, 607px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"8-trier-les-donnees-du-tableau-excel\"><\/span>8. Trier les donn\u00e9es du tableau Excel<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Voici enfin la derni\u00e8re \u00e9tape ce de guide sur comment cr\u00e9er un tableau Excel. Le r\u00e9sultat est un tableau Excel mis en forme. Pour trier ou filtrer les cellules, cliquer sur la fl\u00e8che dans chaque en-t\u00eate de colonne. Par exemple, trier par ann\u00e9e, par total, ou encore s\u00e9lectionner et filtrer uniquement l&rsquo;ann\u00e9e 2021.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"219\" src=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_9_resultat_tableau_avec_filtres-1024x219.png\" alt=\"Tableau Excel mis en forme avec le total des lignes\" class=\"wp-image-3688\" srcset=\"https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_9_resultat_tableau_avec_filtres-1024x219.png 1024w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_9_resultat_tableau_avec_filtres-300x64.png 300w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_9_resultat_tableau_avec_filtres-768x164.png 768w, https:\/\/expert-only.com\/wp-content\/uploads\/2021\/02\/excel_tableau_9_resultat_tableau_avec_filtres.png 1224w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Tableau Excel mis en forme avec le total des lignes<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p><strong><span style=\"text-decoration: underline;\">Note<\/span><\/strong>: pour un affichage plus sobre, d\u00e9sactiver le quadrillage sur l&rsquo;onglet Excel. Pour cela, dans <strong>le menu haut <\/strong>d&rsquo;Excel, sous Affichage, d\u00e9cocher l&rsquo;option Quadrillage.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conclusion sur les avantages des tableaux Excel<\/h3>\n\n\n\n<p>Pourquoi cr\u00e9er et utiliser un tableau Excel ? Les tableaux dans Excel sont un moyen rapide et facile d&rsquo;organiser les donn\u00e9es. Ils peuvent \u00eatre utilis\u00e9s \u00e0 des fins de budg\u00e9tisation, de planification, d&rsquo;analyses ou autres.<\/p>\n\n\n\n<p>Les tableaux peuvent \u00e9galement \u00eatre fusionn\u00e9s avec d&rsquo;autres tableaux, puis tri\u00e9s par en-t\u00eate de colonne ou de ligne pour cr\u00e9er des ensembles de donn\u00e9es plus organis\u00e9s. Un tableau peut aussi utiliser les donn\u00e9es d&rsquo;un autre tableau Excel, dans le m\u00eame fichier ou dans un autre. Pour cela il faut faire une r\u00e9f\u00e9rence \u00e0 d&rsquo;autres cellules ou colonnes Excel. L&rsquo;utilisation de tableaux dans Excel pr\u00e9sente plusieurs avantages, notamment :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Identifier les relations entre les diff\u00e9rentes parties d&rsquo;un ensemble de donn\u00e9es.<\/li>\n\n\n\n<li>Voir facilement les lacunes ou les variations dans les informations<\/li>\n\n\n\n<li>Comparer facilement diff\u00e9rents ensembles avec les totaux et les filtres.<\/li>\n<\/ul>\n\n\n\n<p>Enfin, c&rsquo;est la fin de ce court tutoriel Excel qui explique pas \u00e0 pas comment cr\u00e9er un tableau Excel, puis trier et filtrer les donn\u00e9es. Une variante de ces tableaux encore plus puissante pour l&rsquo;analye des donn\u00e9es sont <a href=\"https:\/\/expert-only.com\/fr\/excel\/tableau-croise-dynamique-excel\/\"><strong>les tableaux crois\u00e9s dynamiques Excel<\/strong><\/a>. Les tableaux dynamiques utilisent aussi une plage de cellule ou un tableau.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-tutoriels-sql-et-it wp-block-embed-tutoriels-sql-et-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"vDaTyAmckt\"><a href=\"https:\/\/expert-only.com\/fr\/excel\/tableau-croise-dynamique-excel\/\">Comment cr\u00e9er un tableau crois\u00e9 dynamique avec Excel ?<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0Comment cr\u00e9er un tableau crois\u00e9 dynamique avec Excel ?\u00a0\u00bb &#8212; Tutoriels SQL et IT\" src=\"https:\/\/expert-only.com\/fr\/excel\/tableau-croise-dynamique-excel\/embed\/#?secret=KCIpZ6ekB6#?secret=vDaTyAmckt\" data-secret=\"vDaTyAmckt\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Tutoriel pas \u00e0 pas pour cr\u00e9er un tableau depuis une plage de donn\u00e9es avec Excel pour les trier, les additionner et les filtrer. Comment cr\u00e9er un tableau Excel et trier les colonnes, puis filtrer les donn\u00e9es ? Cr\u00e9er tout <a class=\"mh-excerpt-more\" href=\"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/\" title=\"Comment cr\u00e9er un tableau Excel ?\">&#8230;<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":10642,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[99],"class_list":{"0":"post-3679","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-excel","8":"tag-fichier"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.7 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comment cr\u00e9er un tableau Excel ? Astuces Excel<\/title>\n<meta name=\"description\" content=\"Apprendre comment cr\u00e9er un tableau Excel, le mettre en forme, pr\u00e9parer les cellules, puis trier et filtrer les donn\u00e9es dans les colonnes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment cr\u00e9er un tableau Excel ?\" \/>\n<meta property=\"og:description\" content=\"Apprendre comment cr\u00e9er un tableau Excel, le mettre en forme, pr\u00e9parer les cellules, puis trier et filtrer les donn\u00e9es dans les colonnes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/\" \/>\n<meta property=\"og:site_name\" content=\"Tutoriels SQL et IT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExpertOnlyCom\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-17T04:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-30T17:07:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expert-only.com\/wp-content\/uploads\/2022\/09\/expresso-coffee-cup-32223910351_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Expert-Only\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@expert_only\" \/>\n<meta name=\"twitter:site\" content=\"@expert_only\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expert-Only\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/excel\\\/comment-creer-un-tableau-excel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/excel\\\/comment-creer-un-tableau-excel\\\/\"},\"author\":{\"name\":\"Expert-Only\",\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/#\\\/schema\\\/person\\\/406a9576b52944f018739a42046873ef\"},\"headline\":\"Comment cr\u00e9er un tableau Excel ?\",\"datePublished\":\"2023-08-17T04:02:00+00:00\",\"dateModified\":\"2023-10-30T17:07:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/excel\\\/comment-creer-un-tableau-excel\\\/\"},\"wordCount\":1140,\"publisher\":{\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/excel\\\/comment-creer-un-tableau-excel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expert-only.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/expresso-coffee-cup-32223910351_1920x1080.jpg\",\"keywords\":[\"Fichier\"],\"articleSection\":[\"Astuces Excel\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/excel\\\/comment-creer-un-tableau-excel\\\/\",\"url\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/excel\\\/comment-creer-un-tableau-excel\\\/\",\"name\":\"Comment cr\u00e9er un tableau Excel ? Astuces Excel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/excel\\\/comment-creer-un-tableau-excel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/excel\\\/comment-creer-un-tableau-excel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expert-only.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/expresso-coffee-cup-32223910351_1920x1080.jpg\",\"datePublished\":\"2023-08-17T04:02:00+00:00\",\"dateModified\":\"2023-10-30T17:07:43+00:00\",\"description\":\"Apprendre comment cr\u00e9er un tableau Excel, le mettre en forme, pr\u00e9parer les cellules, puis trier et filtrer les donn\u00e9es dans les colonnes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/excel\\\/comment-creer-un-tableau-excel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expert-only.com\\\/fr\\\/excel\\\/comment-creer-un-tableau-excel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/excel\\\/comment-creer-un-tableau-excel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expert-only.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/expresso-coffee-cup-32223910351_1920x1080.jpg\",\"contentUrl\":\"https:\\\/\\\/expert-only.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/expresso-coffee-cup-32223910351_1920x1080.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/excel\\\/comment-creer-un-tableau-excel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"en\",\"item\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/24324-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment cr\u00e9er un tableau Excel ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/\",\"name\":\"SQL Server and Data Courses\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/#organization\",\"name\":\"Expert-Only\",\"url\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expert-only.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/cropped-logo_Expert-Only.jpg\",\"contentUrl\":\"https:\\\/\\\/expert-only.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/cropped-logo_Expert-Only.jpg\",\"width\":381,\"height\":174,\"caption\":\"Expert-Only\"},\"image\":{\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExpertOnlyCom\\\/\",\"https:\\\/\\\/x.com\\\/expert_only\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCMS5sR_FwAetB0FmciNvUaA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expert-only.com\\\/fr\\\/#\\\/schema\\\/person\\\/406a9576b52944f018739a42046873ef\",\"name\":\"Expert-Only\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e711e54a9f31bf0cc5e241d2149474e14ce3995669e683ae9e913aa93cd8da1?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e711e54a9f31bf0cc5e241d2149474e14ce3995669e683ae9e913aa93cd8da1?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e711e54a9f31bf0cc5e241d2149474e14ce3995669e683ae9e913aa93cd8da1?s=96&d=identicon&r=g\",\"caption\":\"Expert-Only\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comment cr\u00e9er un tableau Excel ? Astuces Excel","description":"Apprendre comment cr\u00e9er un tableau Excel, le mettre en forme, pr\u00e9parer les cellules, puis trier et filtrer les donn\u00e9es dans les colonnes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment cr\u00e9er un tableau Excel ?","og_description":"Apprendre comment cr\u00e9er un tableau Excel, le mettre en forme, pr\u00e9parer les cellules, puis trier et filtrer les donn\u00e9es dans les colonnes.","og_url":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/","og_site_name":"Tutoriels SQL et IT","article_publisher":"https:\/\/www.facebook.com\/ExpertOnlyCom\/","article_published_time":"2023-08-17T04:02:00+00:00","article_modified_time":"2023-10-30T17:07:43+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/expert-only.com\/wp-content\/uploads\/2022\/09\/expresso-coffee-cup-32223910351_1920x1080.jpg","type":"image\/jpeg"}],"author":"Expert-Only","twitter_card":"summary_large_image","twitter_creator":"@expert_only","twitter_site":"@expert_only","twitter_misc":{"\u00c9crit par":"Expert-Only","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#article","isPartOf":{"@id":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/"},"author":{"name":"Expert-Only","@id":"https:\/\/expert-only.com\/fr\/#\/schema\/person\/406a9576b52944f018739a42046873ef"},"headline":"Comment cr\u00e9er un tableau Excel ?","datePublished":"2023-08-17T04:02:00+00:00","dateModified":"2023-10-30T17:07:43+00:00","mainEntityOfPage":{"@id":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/"},"wordCount":1140,"publisher":{"@id":"https:\/\/expert-only.com\/fr\/#organization"},"image":{"@id":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#primaryimage"},"thumbnailUrl":"https:\/\/expert-only.com\/wp-content\/uploads\/2022\/09\/expresso-coffee-cup-32223910351_1920x1080.jpg","keywords":["Fichier"],"articleSection":["Astuces Excel"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/","url":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/","name":"Comment cr\u00e9er un tableau Excel ? Astuces Excel","isPartOf":{"@id":"https:\/\/expert-only.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#primaryimage"},"image":{"@id":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#primaryimage"},"thumbnailUrl":"https:\/\/expert-only.com\/wp-content\/uploads\/2022\/09\/expresso-coffee-cup-32223910351_1920x1080.jpg","datePublished":"2023-08-17T04:02:00+00:00","dateModified":"2023-10-30T17:07:43+00:00","description":"Apprendre comment cr\u00e9er un tableau Excel, le mettre en forme, pr\u00e9parer les cellules, puis trier et filtrer les donn\u00e9es dans les colonnes.","breadcrumb":{"@id":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#primaryimage","url":"https:\/\/expert-only.com\/wp-content\/uploads\/2022\/09\/expresso-coffee-cup-32223910351_1920x1080.jpg","contentUrl":"https:\/\/expert-only.com\/wp-content\/uploads\/2022\/09\/expresso-coffee-cup-32223910351_1920x1080.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/expert-only.com\/fr\/excel\/comment-creer-un-tableau-excel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"en","item":"https:\/\/expert-only.com\/fr\/24324-2\/"},{"@type":"ListItem","position":2,"name":"Comment cr\u00e9er un tableau Excel ?"}]},{"@type":"WebSite","@id":"https:\/\/expert-only.com\/fr\/#website","url":"https:\/\/expert-only.com\/fr\/","name":"SQL Server and Data Courses","description":"","publisher":{"@id":"https:\/\/expert-only.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expert-only.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/expert-only.com\/fr\/#organization","name":"Expert-Only","url":"https:\/\/expert-only.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expert-only.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/expert-only.com\/wp-content\/uploads\/2017\/09\/cropped-logo_Expert-Only.jpg","contentUrl":"https:\/\/expert-only.com\/wp-content\/uploads\/2017\/09\/cropped-logo_Expert-Only.jpg","width":381,"height":174,"caption":"Expert-Only"},"image":{"@id":"https:\/\/expert-only.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ExpertOnlyCom\/","https:\/\/x.com\/expert_only","https:\/\/www.youtube.com\/channel\/UCMS5sR_FwAetB0FmciNvUaA"]},{"@type":"Person","@id":"https:\/\/expert-only.com\/fr\/#\/schema\/person\/406a9576b52944f018739a42046873ef","name":"Expert-Only","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7e711e54a9f31bf0cc5e241d2149474e14ce3995669e683ae9e913aa93cd8da1?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e711e54a9f31bf0cc5e241d2149474e14ce3995669e683ae9e913aa93cd8da1?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e711e54a9f31bf0cc5e241d2149474e14ce3995669e683ae9e913aa93cd8da1?s=96&d=identicon&r=g","caption":"Expert-Only"}}]}},"_links":{"self":[{"href":"https:\/\/expert-only.com\/fr\/wp-json\/wp\/v2\/posts\/3679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expert-only.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expert-only.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expert-only.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expert-only.com\/fr\/wp-json\/wp\/v2\/comments?post=3679"}],"version-history":[{"count":13,"href":"https:\/\/expert-only.com\/fr\/wp-json\/wp\/v2\/posts\/3679\/revisions"}],"predecessor-version":[{"id":27805,"href":"https:\/\/expert-only.com\/fr\/wp-json\/wp\/v2\/posts\/3679\/revisions\/27805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expert-only.com\/fr\/wp-json\/wp\/v2\/media\/10642"}],"wp:attachment":[{"href":"https:\/\/expert-only.com\/fr\/wp-json\/wp\/v2\/media?parent=3679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expert-only.com\/fr\/wp-json\/wp\/v2\/categories?post=3679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expert-only.com\/fr\/wp-json\/wp\/v2\/tags?post=3679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}